{"id":46016,"date":"2020-07-06T11:21:53","date_gmt":"2020-07-06T09:21:53","guid":{"rendered":"http:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25.jpg"},"modified":"2020-07-06T11:21:53","modified_gmt":"2020-07-06T09:21:53","slug":"ghost-les-eurockeennes-belfort-06-07-2014","status":"inherit","type":"attachment","link":"https:\/\/www.wallendorff.com\/belogue\/ghost-les-eurockeennes-belfort-06-07-2014\/","title":{"rendered":"Ghost @ les Eurock\u00e9ennes, Belfort, 06\/07\/2014"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false},"class_list":["post-46016","attachment","type-attachment","status-inherit","hentry"],"acf":[],"jetpack_shortlink":"https:\/\/wp.me\/a3b35P-bYc","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"780\" height=\"1170\" src=\"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25.jpg 780w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-558x837.jpg 558w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-655x983.jpg 655w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-600x900.jpg 600w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Ghost @ les Eurock\u00e9ennes, Belfort, 06\/07\/2014<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":780,"height":1170,"file":"2020\/07\/20200707-25.jpg","filesize":424582,"sizes":{"woocommerce_thumbnail":{"file":"20200707-25-550x550.jpg","width":550,"height":550,"filesize":60117,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-550x550.jpg"},"woocommerce_gallery_thumbnail":{"file":"20200707-25-220x220.jpg","width":220,"height":220,"filesize":13836,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-220x220.jpg"},"blog-thumb-1":{"file":"20200707-25-468x328.jpg","width":468,"height":328,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-468x328.jpg"},"blog-thumb-2":{"file":"20200707-25-468x468.jpg","width":468,"height":468,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-468x468.jpg"},"blog-thumb-3":{"file":"20200707-25-780x592.jpg","width":780,"height":592,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-780x592.jpg"},"blog-single-1":{"file":"20200707-25-780x635.jpg","width":780,"height":635,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-780x635.jpg"},"portfolio-single-img-4":{"file":"20200707-25-558x837.jpg","width":558,"height":837,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-558x837.jpg"},"portfolio-img-1":{"file":"20200707-25-655x545.jpg","width":655,"height":545,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-655x545.jpg"},"portfolio-img-2":{"file":"20200707-25-655x545.jpg","width":655,"height":545,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-655x545.jpg"},"portfolio-img-3":{"file":"20200707-25-655x983.jpg","width":655,"height":983,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-655x983.jpg"},"shop-category-thumb":{"file":"20200707-25-500x290.jpg","width":500,"height":290,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-500x290.jpg"},"shop_catalog":{"file":"20200707-25-550x550.jpg","width":550,"height":550,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-550x550.jpg"},"shop_thumbnail":{"file":"20200707-25-220x220.jpg","width":220,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-220x220.jpg"},"600x99999":{"file":"20200707-25-600x1170.jpg","width":600,"height":1170,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-600x1170.jpg"},"600x0":{"file":"20200707-25-600x900.jpg","width":600,"height":900,"filesize":90385,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25-600x900.jpg"},"full":{"file":"20200707-25.jpg","width":780,"height":1170,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25.jpg"}},"image_meta":{"aperture":"2.8","credit":"Laurent Wallendorff","camera":"Canon EOS 5D Mark III","caption":"Ghost @ les Eurock\u00e9ennes, Belfort, 06\/07\/2014","created_timestamp":"1404687158","copyright":"L. Wallendorff - www.wallendorff.com","focal_length":"70","iso":"3200","shutter_speed":"0.01","title":"Ghost @ les Eurock\u00e9ennes, Belfort, 06\/07\/2014","orientation":"1","keywords":["2014","Belfort","Eurock\u00e9ennes","Franche Comt\u00e9","Ghost","Les Eurock\u00e9ennes","Loggia","Sermamagny","Territoire de Belfort","alive","concert","festival","gig","les Eurock\u00e9ennes 2014","live","show"]}},"post":null,"source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-25.jpg","_links":{"self":[{"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/media\/46016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/comments?post=46016"}]}}