{"id":46009,"date":"2020-07-06T11:21:40","date_gmt":"2020-07-06T09:21:40","guid":{"rendered":"http:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18.jpg"},"modified":"2020-07-06T11:21:40","modified_gmt":"2020-07-06T09:21:40","slug":"blur-les-eurockeennes-belfort-07-07-2013-2","status":"inherit","type":"attachment","link":"https:\/\/www.wallendorff.com\/belogue\/blur-les-eurockeennes-belfort-07-07-2013-2\/","title":{"rendered":"Blur @ les Eurock\u00e9ennes, Belfort, 07\/07\/2013"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false},"class_list":["post-46009","attachment","type-attachment","status-inherit","hentry"],"acf":[],"jetpack_shortlink":"https:\/\/wp.me\/a3b35P-bY5","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"1170\" height=\"780\" src=\"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18.jpg 1170w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-820x547.jpg 820w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-1116x744.jpg 1116w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-806x537.jpg 806w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-558x372.jpg 558w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-655x437.jpg 655w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-600x400.jpg 600w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Blur @ les Eurock\u00e9ennes, Belfort, 07\/07\/2013<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1170,"height":780,"file":"2020\/07\/20200707-18.jpg","filesize":428775,"sizes":{"woocommerce_thumbnail":{"file":"20200707-18-550x550.jpg","width":550,"height":550,"filesize":57646,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-550x550.jpg"},"woocommerce_gallery_thumbnail":{"file":"20200707-18-220x220.jpg","width":220,"height":220,"filesize":12944,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-220x220.jpg"},"woocommerce_single":{"file":"20200707-18-820x547.jpg","width":820,"height":547,"filesize":79377,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-820x547.jpg"},"blog-thumb-1":{"file":"20200707-18-468x328.jpg","width":468,"height":328,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-468x328.jpg"},"blog-thumb-2":{"file":"20200707-18-468x468.jpg","width":468,"height":468,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-468x468.jpg"},"blog-thumb-3":{"file":"20200707-18-845x592.jpg","width":845,"height":592,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-845x592.jpg"},"blog-single-1":{"file":"20200707-18-1170x635.jpg","width":1170,"height":635,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-1170x635.jpg"},"portfolio-single-img-2":{"file":"20200707-18-1116x744.jpg","width":1116,"height":744,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-1116x744.jpg"},"portfolio-single-img-3":{"file":"20200707-18-806x537.jpg","width":806,"height":537,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-806x537.jpg"},"portfolio-single-img-4":{"file":"20200707-18-558x372.jpg","width":558,"height":372,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-558x372.jpg"},"portfolio-img-1":{"file":"20200707-18-655x545.jpg","width":655,"height":545,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-655x545.jpg"},"portfolio-img-2":{"file":"20200707-18-655x545.jpg","width":655,"height":545,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-655x545.jpg"},"portfolio-img-3":{"file":"20200707-18-655x437.jpg","width":655,"height":437,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-655x437.jpg"},"shop-category-thumb":{"file":"20200707-18-500x290.jpg","width":500,"height":290,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-500x290.jpg"},"shop_catalog":{"file":"20200707-18-550x550.jpg","width":550,"height":550,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-550x550.jpg"},"shop_single":{"file":"20200707-18-820x547.jpg","width":820,"height":547,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-820x547.jpg"},"shop_thumbnail":{"file":"20200707-18-220x220.jpg","width":220,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-220x220.jpg"},"600x99999":{"file":"20200707-18-600x780.jpg","width":600,"height":780,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-600x780.jpg"},"600x0":{"file":"20200707-18-600x400.jpg","width":600,"height":400,"filesize":46056,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18-600x400.jpg"},"full":{"file":"20200707-18.jpg","width":1170,"height":780,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18.jpg"}},"image_meta":{"aperture":"2.8","credit":"Laurent Wallendorff","camera":"Canon EOS 5D Mark II","caption":"Blur @ les Eurock\u00e9ennes, Belfort, 07\/07\/2013","created_timestamp":"1373240436","copyright":"L. Wallendorff","focal_length":"33","iso":"3200","shutter_speed":"0.01","title":"Blur @ les Eurock\u00e9ennes, Belfort, 07\/07\/2013","orientation":"1","keywords":["2013","Belfort","Blur","Damon Albarn","Eurock\u00e9ennes 2013","Franche Comt\u00e9","Les Eurock\u00e9ennes","Territoire de Belfort","alive","concert","festival","gig","live","oui","show"]}},"post":null,"source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2020\/07\/20200707-18.jpg","_links":{"self":[{"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/media\/46009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/comments?post=46009"}]}}