{"id":27986,"date":"2015-07-07T19:45:46","date_gmt":"2015-07-07T17:45:46","guid":{"rendered":"http:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23.jpg"},"modified":"2015-07-07T19:45:46","modified_gmt":"2015-07-07T17:45:46","slug":"les-eurockeennes-belfort-03072015-8","status":"inherit","type":"attachment","link":"https:\/\/www.wallendorff.com\/belogue\/2015\/07\/07\/les-eurockeennes-belfort-jour-1\/les-eurockeennes-belfort-03072015-8\/","title":{"rendered":"Les Eurock\u00e9ennes, Belfort, 03\/07\/2015"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false},"class_list":["post-27986","attachment","type-attachment","status-inherit","hentry"],"acf":[],"jetpack_shortlink":"https:\/\/wp.me\/a3b35P-7ho","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23-300x200.jpg 300w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23-525x350.jpg 525w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23-600x400.jpg 600w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Les Eurock\u00e9ennes, Belfort, 03\/07\/2015<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":533,"file":"2015\/07\/20150707-23.jpg","filesize":224152,"sizes":{"woocommerce_thumbnail":{"file":"20150707-23-550x533.jpg","width":550,"height":533,"filesize":92322,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23-550x533.jpg"},"woocommerce_gallery_thumbnail":{"file":"20150707-23-220x220.jpg","width":220,"height":220,"filesize":18920,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23-220x220.jpg"},"thumbnail":{"file":"20150707-23-188x188.jpg","width":188,"height":188,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23-188x188.jpg"},"medium":{"file":"20150707-23-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23-300x200.jpg"},"blog":{"file":"20150707-23-525x350.jpg","width":525,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23-525x350.jpg"},"600x99999":{"file":"20150707-23-600x533.jpg","width":600,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23-600x533.jpg"},"600x0":{"file":"20150707-23-600x400.jpg","width":600,"height":400,"filesize":71738,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23-600x400.jpg"},"full":{"file":"20150707-23.jpg","width":800,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23.jpg"}},"image_meta":{"aperture":"2.8","credit":"L. Wallendorff","camera":"Canon EOS 6D","caption":"Les Eurock\u00e9ennes, Belfort, 03\/07\/2015","created_timestamp":"1435956870","copyright":"L. Wallendorff - www.wallendorff.com","focal_length":"15","iso":"160","shutter_speed":"0.02","title":"Les Eurock\u00e9ennes, Belfort, 03\/07\/2015","orientation":"1","keywords":["2015","Belfort","France","Franche-Comt\u00e9","Les Eurock\u00e9ennes","Sermamagny","Territoire de Belfort","alive","ambiance","festival","les Eurock\u00e9ennes de Belfort 2015","public"]}},"post":27962,"source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-23.jpg","_links":{"self":[{"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/media\/27986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/comments?post=27986"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":27962,"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/posts\/27962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}