{"id":27974,"date":"2015-07-07T19:45:30","date_gmt":"2015-07-07T17:45:30","guid":{"rendered":"http:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11.jpg"},"modified":"2015-07-07T19:45:30","modified_gmt":"2015-07-07T17:45:30","slug":"royal-blood-les-eurockeennes-belfort-03072015-9","status":"inherit","type":"attachment","link":"https:\/\/www.wallendorff.com\/belogue\/2015\/07\/07\/les-eurockeennes-belfort-jour-1\/royal-blood-les-eurockeennes-belfort-03072015-9\/","title":{"rendered":"Royal Blood @ les Eurock\u00e9ennes, Belfort, 03\/07\/2015"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false},"class_list":["post-27974","attachment","type-attachment","status-inherit","hentry"],"acf":[],"jetpack_shortlink":"https:\/\/wp.me\/a3b35P-7hc","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11-300x200.jpg 300w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11-525x350.jpg 525w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11-600x400.jpg 600w, https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":533,"file":"2015\/07\/20150707-11.jpg","filesize":179306,"sizes":{"woocommerce_thumbnail":{"file":"20150707-11-550x533.jpg","width":550,"height":533,"filesize":68862,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11-550x533.jpg"},"woocommerce_gallery_thumbnail":{"file":"20150707-11-220x220.jpg","width":220,"height":220,"filesize":15468,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11-220x220.jpg"},"thumbnail":{"file":"20150707-11-188x188.jpg","width":188,"height":188,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11-188x188.jpg"},"medium":{"file":"20150707-11-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11-300x200.jpg"},"blog":{"file":"20150707-11-525x350.jpg","width":525,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11-525x350.jpg"},"600x99999":{"file":"20150707-11-600x533.jpg","width":600,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11-600x533.jpg"},"600x0":{"file":"20150707-11-600x400.jpg","width":600,"height":400,"filesize":55070,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11-600x400.jpg"},"full":{"file":"20150707-11.jpg","width":800,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11.jpg"}},"image_meta":{"aperture":"3.2","credit":"L. Wallendorff","camera":"Canon EOS 6D","caption":"","created_timestamp":"1435953378","copyright":"L. Wallendorff - www.wallendorff.com","focal_length":"70","iso":"1000","shutter_speed":"0.004","title":"Royal Blood @ les Eurock\u00e9ennes, Belfort, 03\/07\/2015","orientation":"1","keywords":["2015","Belfort","France","Franche-Comt\u00e9","Les Eurock\u00e9ennes","Royal Blood","Sermamagny","Territoire de Belfort","alive","festival","les Eurock\u00e9ennes de Belfort 2015"]}},"post":27962,"source_url":"https:\/\/www.wallendorff.com\/belogue\/wp-content\/uploads\/2015\/07\/20150707-11.jpg","_links":{"self":[{"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/media\/27974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/comments?post=27974"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":27962,"href":"https:\/\/www.wallendorff.com\/belogue\/wp-json\/wp\/v2\/posts\/27962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}